{"id":9586,"date":"2019-03-25T15:40:00","date_gmt":"2019-03-25T15:40:00","guid":{"rendered":"http:\/\/icg-institut.de\/?p=9586"},"modified":"2020-10-28T12:44:15","modified_gmt":"2020-10-28T12:44:15","slug":"karin-barthelmes-wehr-ist-neue-vorsitzende-des-von-der-uno-initiierten-projektes-international-ethics-standards","status":"publish","type":"post","link":"https:\/\/icg-institut.de\/de\/karin-barthelmes-wehr-ist-neue-vorsitzende-des-von-der-uno-initiierten-projektes-international-ethics-standards\/","title":{"rendered":"Karin Barthelmes-Wehr ist neue Vorsitzende des von der UNO initiierten Projektes \u201eInternational Ethics Standards"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Pressemitteilung<br>Karin Barthelmes-Wehr ist neue Vorsitzende des von der UNO initiierten Projektes \u201eInternational Ethics Standards\u201c<\/strong><\/p>\n\n\n\n<p><br>Berlin, 25. M\u00e4rz 2019 \u2013 Die langj\u00e4hrige Gesch\u00e4ftsf\u00fchrerin des Instituts f\u00fcr Corporate Governance in der deutschen Immobilienwirtschaft (ICG), Karin Barthelmes-Wehr, ist von den mehr als 130 Mitglieds-Organisationen und Verb\u00e4nden der International Ethics Standards Coalition (<a href=\"https:\/\/ies-coalition.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">IES \u2013 www.iescoalition.org<\/a>) zur neuen Vorsitzenden gew\u00e4hlt worden.<\/p>\n\n\n\n<p><br>IES ist ein Projekt, das vor f\u00fcnf Jahren bei der UNO in New York initiiert wurde und das ehrgeizige Ziel hat, einen einheitlichen Ethik-Kodex f\u00fcr die weltweite Immobilienwirtschaft zu schaffen und zu implementieren. Ihm haben sich verschiedenste Branchen-Verb\u00e4nde aus allen Teilen der Erde angeschlossen, die diesen Kodex aktuell bei ihren Mitgliedern umsetzen.<\/p>\n\n\n\n<p><br>\u201eIch freue mich sehr, dieses wichtige Projekt zu leiten. Wir haben beim ICG \u00fcber 17 Jahre Erfahrung in der Entwicklung und Implementierung von Kodizes und Leitlinien im deutschen Immobilienmarkt \u2013 dies lasse ich seit der Gr\u00fcndung von IES in die internationale Arbeit hieran einflie\u00dfen,\u201c so Karin Barthelmes-Wehr. Und sie betont: \u201eVor uns liegt noch ein weiter Weg, denn die bei IES mitwirkenden Organisationen kommen aus sehr unterschiedlichen M\u00e4rkten. Aber es gibt bereits erste Erfolge in der Umsetzung des Kodexes und jeder Weg beginnt mit den ersten Schritten.\u201c<\/p>\n\n\n\n<p><br>Das ICG hat sich im Herbst 2002 mit dem Ziel konstituiert, Wettbewerbschancen der deutschen Immobilienbranche durch die Entwicklung sowie Um- und Durchsetzung von Standards f\u00fcr nachhaltige, werteorientierte Unternehmensf\u00fchrung zu verbessern. Zur Umsetzung der Leitlinien und Standards organisiert das ICG regelm\u00e4\u00dfig Best Practice-Workshops, Arbeitsgruppen f\u00fcr Entscheider und veranstaltet j\u00e4hrlich das Jahresevent \u201eThe German Real Estate Summit\u201c. Mit den Seminaren der ICG Real Estate Board Academy soll zuk\u00fcnftigen und aktuellen Aufsichts- und Beir\u00e4ten das notwendige R\u00fcstzeug f\u00fcr verantwortungsvolles, erfolgreiches Handeln vermittelt werden. Des Weiteren gibt das ICG eine Fachzeitschrift sowie regelm\u00e4\u00dfig praktische Handreichungen und Leitf\u00e4den f\u00fcr die Branche heraus. \u00dcber 80 f\u00fchrende Unternehmen der Immobilien-Branche haben sich dem Institut als Firmenmitglieder angeschlossen, fast ebenso viele prominente Vertreter der Branche geh\u00f6ren ihm auch als pers\u00f6nliche Mitglieder an. Das ICG bearbeitet f\u00fcr und gemeinsam mit dem ZIA Zentraler Immobilien Ausschuss e.V. Themen rund um nachhaltige Unternehmensf\u00fchrung.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Das ICG<\/strong><br>Das ICG versteht sich als Think-and-Do-Tank. Es hat sich im Herbst 2002 mit dem Ziel konstituiert, Wettbewerbschancen der deutschen Immobilienbranche durch die Entwicklung sowie Um- und Durchsetzung von Standards f\u00fcr nachhaltige, werteorientierte Unternehmensf\u00fchrung zu verbessern. Zur Umsetzung der Leitlinien und Standards organisiert das ICG regelm\u00e4\u00dfig Best Practice Workshops, Arbeitsgruppen f\u00fcr Entscheider und veranstaltet j\u00e4hrlich das Jahresevent \u201eThe German Real Estate Summit\u201c. Mit den Seminaren der ICG Real Estate Board Academy soll zuk\u00fcnftigen und aktuellen Aufsichts- und Beir\u00e4ten das notwendige Know-how f\u00fcr verantwortungsvolles, erfolgreiches Handeln vermittelt werden.<\/p>\n\n\n\n<p><strong>Kontakt<\/strong><br>Karin Barthelmes-Wehr<br>Gesch\u00e4ftsf\u00fchrerin<br>Institut f\u00fcr Corporate Governance in der deutschen Immobilienwirtschaft e.V.<br>Tel. +49 211 59 81 55 81<br>Fax: +49 211 59 81 55 82<br>Mobil\/Cell Phone: +49 170 4095 167<br>E-Mail: barthelmes@icg-institut.de<\/p>\n\n\n\n<p><strong>B\u00fcro Gesch\u00e4ftsstelle:<\/strong><br>Leipziger Platz 9<br>10117 Berlin<br>Tel. +49 30 202 1585 55<br>Fax: +49 30 202 1585 29<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PressemitteilungKarin Barthelmes-Wehr ist neue Vorsitzende des von der UNO initiierten Projektes \u201eInternational Ethics Standards\u201c Berlin, 25. M\u00e4rz 2019 \u2013 Die langj\u00e4hrige Gesch\u00e4ftsf\u00fchrerin des Instituts f\u00fcr Corporate Governance in der deutschen Immobilienwirtschaft (ICG), Karin Barthelmes-Wehr, ist von den mehr als 130 Mitglieds-Organisationen und Verb\u00e4nden der International Ethics Standards Coalition (IES \u2013 www.iescoalition.org) zur neuen Vorsitzenden gew\u00e4hlt [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":9818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:paragraph -->\n<p><strong>Berlin, 26.05.2020<\/strong> \u2013 Der Zentrale Immobilien Ausschuss ZIA, Spitzenverband der Immobilienwirtschaft, und das Institut f\u00fcr Corporate Governance in der deutschen Immobilienwirtschaft (ICG) machen anl\u00e4sslich des heutigen 8. Deutschen DiversityTages auf die hohe Bedeutung dieses Themas insbesondere f\u00fcr die Immobilienwirtschaft aufmerksam. \u201eWir sehen aktuell, dass Corona die Arbeitswelt ver\u00e4ndern wird\u201c, sagt ZIA-Vizepr\u00e4sidentin B\u00e4rbel Schomberg. \u201eZahlreiche Menschen sind in Kurzarbeit und arbeiten im Home Office, viele Unternehmen beklagen Einnahmeausf\u00e4lle und sind insolvenzbedroht. Die Frage ist nicht, ob diese Entwicklungen unsere Gesellschaft ver\u00e4ndern, sondern auf welche Art und Weise. Umso wichtiger ist es aber, dass wir den Diversity-Gedanken weiter vorantreiben \u2013 erst recht in dieser schwierigen Zeit. Denn auch hiervon h\u00e4ngt die Zukunftsf\u00e4higkeit und die Wettbewerbsf\u00e4higkeit der Branchen ab. Das gilt vor allem f\u00fcr die Immobilienwirtschaft, denn wir sind Teil der L\u00f6sungen f\u00fcr gesamtgesellschaftliche Herausforderungen \u2013 sei es das bezahlbare Bauen und Wohnen, den Klimaschutz oder die Digitalisierung. Hierf\u00fcr brauchen wir die besten K\u00f6pfe und ein kluges Diversity Management in den Unternehmen, das zum wirtschaftlichen Erfolg beitr\u00e4gt. Wird Diversity vernachl\u00e4ssigt, sind die Krisenzeiten umso h\u00e4rter.\u201c <br><br>Werner Knips, stellvertretender Vorstandsvorsitzender des ICG und Mitglied des ZIA Pr\u00e4sidiums, erg\u00e4nzt:\u201eKrisen bieten Chancen f\u00fcr neues Denken und Handeln. Themen wie Professionalit\u00e4t, Transparenz, Image, Nachhaltigkeit und Verantwortung m\u00fcssen in der Immobilienwirtschaft k\u00fcnftig eine zentrale Rolle spielen. Im Bereich Diversity werden Potentiale bisher noch nicht gehoben \u2013 das wird uns nach der Krise auf die F\u00fc\u00dfe fallen. Diverse Teams sind good for business and growth!\u201c<br><br><strong>Gemeinsamer Video-Cast von ZIA und ICG<\/strong> <br>Beide Verb\u00e4nde haben zum Deutschen Diversity-Tag einen Video-Cast produziert, in dem f\u00fcnf weibliche F\u00fchrungskr\u00e4fte der Immobilienbranche ihre Sicht auf die Krise und die Auswirkungen schildern und auf die Erfahrungen und das Gelernte aus der Krise hinweisen. Das Video finden Sie unter diesem <a rel=\"noreferrer noopener\" href=\"https:\/\/youtu.be\/PVLz2gQC2y0\" target=\"_blank\">LINK<\/a>. <br><br><strong>Diversity-Aktivit\u00e4ten des ZIA: Trendkarten, Kodex und Toolbox<\/strong> <br>Das Thema Diversity steht seit mehreren Jahren fest auf der Agenda des ZIA und wird durch unterschiedliche Aktivit\u00e4ten unterstrichen. Gemeinsam mit dem Fraunhofer-Institut f\u00fcr System- und Innovationsforschung ISI haben der ZIA und seine Mitglieder zudem \u00fcber mehrere Monate hinweg an sogenannten DiversityTrendkarten gearbeitet. \u201eDie Karten zeigen didaktisch sehr eindrucksvoll die globalen, gesellschaftlichen Zukunftstrends und deren Relevanz f\u00fcr die Arbeitswelt und die daraus resultierenden Konsequenzen f\u00fcr ein zukunftsorientiertes Diversity Management auf\u201c, sagt Schomberg. Die Karten finden Sie unter diesem <a rel=\"noreferrer noopener\" href=\"https:\/\/www.zia-deutschland.de\/fileadmin\/Redaktion\/Meta_Service\/PDF\/zia_diversity_trendkarten.pdf\" target=\"_blank\">LINK<\/a>.<br><br>Der ZIA hat dar\u00fcber hinaus gemeinsam mit seinen Mitgliedern und dem ICG einen Diversity-Kodex entwickelt, den Sie auf der ZIA-Themenseite \u201eDiversity\u201c unter diesem <a rel=\"noreferrer noopener\" href=\"https:\/\/www.zia-deutschland.de\/themen\/diversity\/\" target=\"_blank\">LINK<\/a> finden. Dort ist auch die Diversity Toolbox als Download verf\u00fcgbar. <br><br><strong>Diversity-Aktivit\u00e4ten des ICG: Mentoring-Programm, Workshops und Veranstaltungen<\/strong> <br>Das ICG befasst sich ebenfalls seit vielen Jahren im Rahmen seines Programms \u201eDiversity on Boards\u201c mit dem Thema \u2013 und zwar im Sinne einer Vielfalt des Denkens. In einem ersten Schritt hat sich das Institut mit dem Mentoring-Programm \u201eWomen on Boards\u201c zum Ziel gesetzt, die Anzahl von Frauen in Aufsichts- und Beir\u00e4ten wie Gesch\u00e4ftsf\u00fchrungs- und Vorstandsgremien in der deutschen Immobilienwirtschaft deutlich zu erh\u00f6hen. In mehreren Tandemrunden haben sich bisher rund 40 Mentees mit hochkar\u00e4tigen Mentoren und Mentorinnen zusammengefunden. Das ICG vernetzt diese Frauen und bietet dar\u00fcber hinaus Veranstaltungen und Workshops zu Themen rund um ganzheitliche Diversity an.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br><strong>Der ZIA<\/strong><br>Der Zentrale Immobilien Ausschuss ZIA ist der Spitzenverband der Immobilienwirtschaft. Er spricht durch seine Mitglieder, darunter 28 Verb\u00e4nde, f\u00fcr rund 37.000 Unternehmen der Branche entlang der gesamten Wertsch\u00f6pfungskette. Der ZIA gibt der Immobilienwirtschaft in ihrer ganzen Vielfalt eine umfassende und einheitliche Interessenvertretung, die ihrer Bedeutung f\u00fcr die Volkswirtschaft entspricht. Als Unternehmer- und Verb\u00e4ndeverband verleiht er der gesamten Immobilienwirtschaft<br>eine Stimme auf nationaler und europ\u00e4ischer Ebene \u2013 und im Bundesverband der deutschen Industrie (BDI). Pr\u00e4sident des Verbandes ist Dr. Andreas Mattner.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Kontakt<\/strong><br>Andr\u00e9 Hentz<br>ZIA Zentraler Immobilien Ausschuss e.V.<br>Leipziger Platz 9<br>10117 Berlin<br>Tel.: 030\/20 21 585 23<br>E-Mail: andre.hentz@zia-deutschland.de<br>Internet: www.zia-deutschland.de<br><br><br><strong>Das ICG<\/strong><br>Das ICG versteht sich als Think-and-Do-Tank. Es hat sich im Herbst 2002 mit dem Ziel konstituiert, Wettbewerbschancen der deutschen Immobilienbranche durch die Entwicklung sowie Um- und Durchsetzung von Standards f\u00fcr nachhaltige, werteorientierte Unternehmensf\u00fchrung zu verbessern. Zur Umsetzung der Leitlinien und Standards organisiert das ICG regelm\u00e4\u00dfig Best Practice Workshops, Arbeitsgruppen f\u00fcr Entscheider und veranstaltet j\u00e4hrlich das Jahresevent \u201eThe German Real Estate Summit\u201c. Mit den Seminaren der ICG Real Estate Board Academy soll zuk\u00fcnftigen und aktuellen Aufsichts- und Beir\u00e4ten das notwendige Know-how f\u00fcr verantwortungsvolles, erfolgreiches Handeln vermittelt werden.<br><br><strong>Kontakt<\/strong><br>Karin Barthelmes-Wehr<br>Gesch\u00e4ftsf\u00fchrerin<br>Institut f\u00fcr Corporate Governance in der deutschen Immobilienwirtschaft e.V.<br>Tel. +49 211 59 81 55 81<br>Fax: +49 211 59 81 55 82<br>Mobil\/Cell Phone: +49 170 4095 167<br>E-Mail: barthelmes@icg-institut.de<br><br><strong>B\u00fcro Gesch\u00e4ftsstelle:<\/strong><br>Leipziger Platz 9<br>10117 Berlin<br>Tel. +49 30 202 1585 55<br>Fax: +49 30 202 1585 29<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":""},"categories":[55],"tags":[],"_links":{"self":[{"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/posts\/9586"}],"collection":[{"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/comments?post=9586"}],"version-history":[{"count":0,"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/posts\/9586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/media\/9818"}],"wp:attachment":[{"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/media?parent=9586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/categories?post=9586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icg-institut.de\/de\/wp-json\/wp\/v2\/tags?post=9586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}